{"id":3363,"date":"2022-03-27T18:07:36","date_gmt":"2022-03-27T16:07:36","guid":{"rendered":"https:\/\/www.bhak-eisenstadt.at\/2016\/?p=3363"},"modified":"2022-03-27T18:07:38","modified_gmt":"2022-03-27T16:07:38","slug":"schule-meets-schnee-skitage-am-semmering","status":"publish","type":"post","link":"https:\/\/www.bhak-eisenstadt.at\/2016\/schule-meets-schnee-skitage-am-semmering\/","title":{"rendered":"Schule meets Schnee: Skitage am Semmering"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p>Die Zeiten sind herausfordernd, insbesondere auch f\u00fcr Jugendliche. In den Jahren der Pandemie haben Sch\u00fclerinnen und Sch\u00fcler auf vieles verzichten m\u00fcssen: Skikurse, Sprachreisen und andere Schulveranstaltungen konnten nicht stattfinden. Dabei sind es gerade jene Unternehmungen, die Teamgeist und Schulklima f\u00f6rdern und \u2013 bisweilen lange \u00fcber die Schulzeit hinweg \u2013 in Erinnerung bleiben.<\/p>\n\n\n\n<p>Ein Versuch, dies zu kompensieren, waren die Skitage der BHAK\/BHAS Eisenstadt in Stuhleck\/Semmering: Drei Tage sind Lehrer*innen und Sch\u00fcler*innen auf Tuchf\u00fcllung mit den Pisten des Skigebiets Stuhleck gegangen \u2013 wiewohl die aktuelle Situation die st\u00e4ndige R\u00fcckreise erforderte. &nbsp;<\/p>\n\n\n\n<p>Neben diesem sozialen Ansinnen stand auch das Sportliche im Mittelpunkt: \u201eWir m\u00f6chten den Sch\u00fclerinnen und Sch\u00fclern die M\u00f6glichkeit geben, sich an der frischen Luft zu bewegen und unter professioneller Anleitung die Freuden des Wintersports kennenzulernen.\u201c, so die Organisatoren Prof. Altenburger und Prof. Razstovic.<\/p>\n\n\n\n<p>Die Freude war auf allen Seiten entsprechend gro\u00df.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-768x1024.jpg\" alt=\"\" data-id=\"3368\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-scaled.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3368#main\" class=\"wp-image-3368\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-768x1024.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-225x300.jpg 225w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-1152x1536.jpg 1152w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-1536x2048.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage2-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\">fbt<\/figcaption><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-768x1024.jpg\" alt=\"\" data-id=\"3369\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-scaled.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3369#main\" class=\"wp-image-3369\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-768x1024.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-225x300.jpg 225w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-1152x1536.jpg 1152w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-1536x2048.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage3-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-768x1024.jpg\" alt=\"\" data-id=\"3370\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-scaled.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3370#main\" class=\"wp-image-3370\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-768x1024.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-225x300.jpg 225w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-1152x1536.jpg 1152w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-1536x2048.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/03\/Schitage4-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Zeiten sind herausfordernd, insbesondere auch f\u00fcr Jugendliche. In den Jahren der Pandemie haben Sch\u00fclerinnen und Sch\u00fcler auf vieles verzichten m\u00fcssen: Skikurse, Sprachreisen und andere Schulveranstaltungen konnten nicht stattfinden. Dabei sind es gerade jene Unternehmungen, die Teamgeist und Schulklima f\u00f6rdern und \u2013 bisweilen lange \u00fcber die Schulzeit hinweg \u2013 in Erinnerung bleiben. Ein Versuch, dies <a class=\"more-link\" href=\"https:\/\/www.bhak-eisenstadt.at\/2016\/schule-meets-schnee-skitage-am-semmering\/\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":3372,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,4],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3363"}],"collection":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/comments?post=3363"}],"version-history":[{"count":2,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3363\/revisions"}],"predecessor-version":[{"id":3374,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3363\/revisions\/3374"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/media\/3372"}],"wp:attachment":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/media?parent=3363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/categories?post=3363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/tags?post=3363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}