{"id":3413,"date":"2022-05-30T18:18:04","date_gmt":"2022-05-30T16:18:04","guid":{"rendered":"https:\/\/www.bhak-eisenstadt.at\/2016\/?p=3413"},"modified":"2022-05-30T18:18:05","modified_gmt":"2022-05-30T16:18:05","slug":"schmetterlinge-an-der-schule-bildung-oekologisch-und-nachhaltig","status":"publish","type":"post","link":"https:\/\/www.bhak-eisenstadt.at\/2016\/schmetterlinge-an-der-schule-bildung-oekologisch-und-nachhaltig\/","title":{"rendered":"Schmetterlinge an der Schule \u2013 Bildung \u00f6kologisch und nachhaltig"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><em>BHAK\/BHAS Eisenstadt er\u00f6ffnet Erasmus+ Blumenwiese<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"458\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_1-1024x458.png\" alt=\"\" class=\"wp-image-3414\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_1-1024x458.png 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_1-300x134.png 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_1-768x344.png 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_1-1536x687.png 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_1-2048x916.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>In Zusammenarbeit mit der Stadt Eisenstadt hat die BHAK\/BHAS eine \u201eErasmus-Blumenwiese\u201c angelegt. Die Gr\u00fcnfl\u00e4che ist einerseits ein Freiluft-Lernort, andererseits aber m\u00f6chte sie auch dem Insektensterben entgegenwirken. Denn dieses f\u00fchrt nicht nur zum Verlust \u00f6kologischer Vielfalt, sondern bedroht ganze Lebensr\u00e4ume \u2013 und damit den gesamten Planeten.<\/p>\n\n\n\n<p>Im Rahmen des Erasmus+-Projekts \u201eHeute f\u00fcr die Welt von morgen\u201c wurde die Blumenwiese eingefriedet, bepflanzt und erweitert. Die Blumensamen hat wieder die Stadt Eisenstadt zur Verf\u00fcgung gestellt. Es sind jene, die bei den Eisenst\u00e4dter Schmetterlingswiesen verwendet werden, ein Projekt, das seit 2017 besteht. Im Zuge der Er\u00f6ffnung hat B\u00fcrgermeister Mag. Thomas Steiner die jungen G\u00e4rtnerinnen und G\u00e4rtner besucht und ihr \u00f6kologisches Engagement gelobt. Das Projekt wird innerschulisch von Prof. Dr. Dipl.-Ing. Valeria Ringhofer geleitet und von der \u00d6kolog-Referentin Prof. Mag. Lisa Josk unterst\u00fctzt.<\/p>\n\n\n\n<p>\u201eDie Sch\u00fclerinnen und Sch\u00fcler pflanzen am Schulgel\u00e4nde eine Blumenwiese, sie beforschen und betreuen diese und beobachten ihre Entwicklung. Wir wollen junge Menschen f\u00fcr verschiedenste Lebensr\u00e4ume sensibilisieren und die Bedeutung eines \u00f6kologischen Gleichgewichts bzw. einer nachhaltigen Lebensweise vermitteln\u201c, so Schulleiter Prof. Mag. Reinhard Gaul.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"678\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5-1024x678.jpg\" alt=\"\" data-id=\"3418\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3418#main\" class=\"wp-image-3418\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5-1024x678.jpg 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5-300x199.jpg 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5-768x509.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5-1536x1017.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_5-2048x1356.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"678\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4-1024x678.jpg\" alt=\"\" data-id=\"3417\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3417#main\" class=\"wp-image-3417\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4-1024x678.jpg 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4-300x199.jpg 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4-768x509.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4-1536x1017.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_4-2048x1356.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"678\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6-1024x678.jpg\" alt=\"\" data-id=\"3419\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3419#main\" class=\"wp-image-3419\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6-1024x678.jpg 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6-300x199.jpg 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6-768x509.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6-1536x1017.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_6-2048x1356.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"678\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2-1024x678.jpg\" alt=\"\" data-id=\"3415\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3415#main\" class=\"wp-image-3415\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2-1024x678.jpg 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2-300x199.jpg 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2-768x509.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2-1536x1017.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_2-2048x1356.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"678\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3-1024x678.jpg\" alt=\"\" data-id=\"3416\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3.jpg\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3416#main\" class=\"wp-image-3416\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3-1024x678.jpg 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3-300x199.jpg 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3-768x509.jpg 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3-1536x1017.jpg 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Blumenwiese_3-2048x1356.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" width=\"606\" height=\"173\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Logo_Erasmus.jpg\" alt=\"\" class=\"wp-image-3385 size-full\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Logo_Erasmus.jpg 606w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2022\/05\/Logo_Erasmus-300x86.jpg 300w\" sizes=\"(max-width: 606px) 100vw, 606px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>&#8222;Dieses Projekt wurde mit Unterst\u00fctzung der Europ\u00e4ischen Kommission finanziert. Die Verantwortung f\u00fcr den Inhalt dieser Ver\u00f6ffentlichung tr\u00e4gt allein der Verfasser; die Kommission haftet nicht f\u00fcr die weitere Verwendung der darin enthaltenen Angaben.&#8220;<\/p>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BHAK\/BHAS Eisenstadt er\u00f6ffnet Erasmus+ Blumenwiese In Zusammenarbeit mit der Stadt Eisenstadt hat die BHAK\/BHAS eine \u201eErasmus-Blumenwiese\u201c angelegt. Die Gr\u00fcnfl\u00e4che ist einerseits ein Freiluft-Lernort, andererseits aber m\u00f6chte sie auch dem Insektensterben entgegenwirken. Denn dieses f\u00fchrt nicht nur zum Verlust \u00f6kologischer Vielfalt, sondern bedroht ganze Lebensr\u00e4ume \u2013 und damit den gesamten Planeten. Im Rahmen des Erasmus+-Projekts \u201eHeute <a class=\"more-link\" href=\"https:\/\/www.bhak-eisenstadt.at\/2016\/schmetterlinge-an-der-schule-bildung-oekologisch-und-nachhaltig\/\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":3420,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,4],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3413"}],"collection":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/comments?post=3413"}],"version-history":[{"count":1,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3413\/revisions"}],"predecessor-version":[{"id":3422,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3413\/revisions\/3422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/media\/3420"}],"wp:attachment":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/media?parent=3413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/categories?post=3413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/tags?post=3413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}