{"id":3714,"date":"2023-02-23T11:21:29","date_gmt":"2023-02-23T10:21:29","guid":{"rendered":"https:\/\/www.bhak-eisenstadt.at\/2016\/?p=3714"},"modified":"2023-02-23T11:21:31","modified_gmt":"2023-02-23T10:21:31","slug":"fleissige-bienen-beutenspende","status":"publish","type":"post","link":"https:\/\/www.bhak-eisenstadt.at\/2016\/fleissige-bienen-beutenspende\/","title":{"rendered":"Flei\u00dfige Bienen \u2013 Beutenspende"},"content":{"rendered":"\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column\" style=\"flex-basis:100%\">\n<p>Die Junior Company der 2BK unseres Hauses hat ein naturnahes, nachhaltiges Produkt im Sortiment: Honigabf\u00fcllungen aus eigener Erzeugung. Unter der Leitung von Prof. MMag. Christian Langecker, Betreuer des jungen Unternehmens und leidenschaftlicher Imker, waren die Sch\u00fclerinnen und Sch\u00fcler f\u00fcr die gesamte Herstellung, das Marketing und den Verkauf verantwortlich. Am Tag der offenen T\u00fcr wurden die Produkte an interessierte Kundinnen und Kunden feilgeboten. Hierf\u00fcr hat LH-Stv<sup>in<\/sup> Mag.<sup>a<\/sup> Astrid Eisenkopf die Bienenbeuten gesponsert. Als Dank \u00fcberreichten ihr die Sch\u00fclerinnen und Sch\u00fcler verschiedene Honigabf\u00fcllungen mit eigens designtem Logo. \u201eEs ist unglaublich spannend, ein Produkt von der Wiege bis zur Bahre zu begleiten\u201c, so eine Sch\u00fclerin der Klasse. Wir danken Frau LH-Stv<sup>in<\/sup> f\u00fcr ihre Spende und w\u00fcnschen guten Appetit!<\/p>\n<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"393\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1-1024x393.png\" alt=\"\" data-id=\"3716\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1.png\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3716#main\" class=\"wp-image-3716\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1-1024x393.png 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1-300x115.png 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1-768x295.png 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1-1536x590.png 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig1-2048x786.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"455\" src=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2-1024x455.png\" alt=\"\" data-id=\"3715\" data-full-url=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2.png\" data-link=\"https:\/\/www.bhak-eisenstadt.at\/2016\/?attachment_id=3715#main\" class=\"wp-image-3715\" srcset=\"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2-1024x455.png 1024w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2-300x133.png 300w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2-768x341.png 768w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2-1536x683.png 1536w, https:\/\/www.bhak-eisenstadt.at\/2016\/wp-content\/uploads\/2023\/02\/Honig2-2048x910.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Die Junior Company der 2BK unseres Hauses hat ein naturnahes, nachhaltiges Produkt im Sortiment: Honigabf\u00fcllungen aus eigener Erzeugung. Unter der Leitung von Prof. MMag. Christian Langecker, Betreuer des jungen Unternehmens und leidenschaftlicher Imker, waren die Sch\u00fclerinnen und Sch\u00fcler f\u00fcr die gesamte Herstellung, das Marketing und den Verkauf verantwortlich. Am Tag der offenen T\u00fcr wurden die <a class=\"more-link\" href=\"https:\/\/www.bhak-eisenstadt.at\/2016\/fleissige-bienen-beutenspende\/\">Weiterlesen&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":3717,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,4],"tags":[],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3714"}],"collection":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/comments?post=3714"}],"version-history":[{"count":1,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3714\/revisions"}],"predecessor-version":[{"id":3718,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/posts\/3714\/revisions\/3718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/media\/3717"}],"wp:attachment":[{"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/media?parent=3714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/categories?post=3714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bhak-eisenstadt.at\/2016\/wp-json\/wp\/v2\/tags?post=3714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}